{"id":25594,"date":"2025-09-04T10:57:22","date_gmt":"2025-09-04T14:57:22","guid":{"rendered":"https:\/\/www.flaquarium.org\/lideres-en-conservacion\/prioridades-de-conservacion\/"},"modified":"2026-02-09T14:57:58","modified_gmt":"2026-02-09T19:57:58","slug":"prioridades-de-conservacion","status":"publish","type":"page","link":"https:\/\/www.flaquarium.org\/es\/conservacion\/lideres-en-conservacion\/prioridades-de-conservacion\/","title":{"rendered":"Prioridades de conservaci\u00f3n"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":25570,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"class_list":["post-25594","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prioridades de conservaci\u00f3n | The Florida Aquarium<\/title>\n<meta name=\"description\" content=\"En The Florida Aquarium, la conservaci\u00f3n es una forma de vida para todos los miembros de nuestro equipo, en todos los departamentos y funciones. Mira c\u00f3mo estamos poniendo en pr\u00e1ctica nuestras cuatro prioridades de conservaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.flaquarium.org\/es\/conservacion\/lideres-en-conservacion\/prioridades-de-conservacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prioridades de conservaci\u00f3n | The Florida Aquarium\" \/>\n<meta property=\"og:description\" content=\"En The Florida Aquarium, la conservaci\u00f3n es una forma de vida para todos los miembros de nuestro equipo, en todos los departamentos y funciones. Mira c\u00f3mo estamos poniendo en pr\u00e1ctica nuestras cuatro prioridades de conservaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.flaquarium.org\/es\/conservacion\/lideres-en-conservacion\/prioridades-de-conservacion\/\" \/>\n<meta property=\"og:site_name\" content=\"The Florida Aquarium\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/floridaaquarium\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-09T19:57:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@floridaaquarium\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.flaquarium.org\\\/es\\\/conservacion\\\/lideres-en-conservacion\\\/prioridades-de-conservacion\\\/\",\"url\":\"https:\\\/\\\/www.flaquarium.org\\\/es\\\/conservacion\\\/lideres-en-conservacion\\\/prioridades-de-conservacion\\\/\",\"name\":\"Prioridades de conservaci\u00f3n | The Florida Aquarium\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.flaquarium.org\\\/es\\\/#website\"},\"datePublished\":\"2025-09-04T14:57:22+00:00\",\"dateModified\":\"2026-02-09T19:57:58+00:00\",\"description\":\"En The Florida Aquarium, la conservaci\u00f3n es una forma de vida para todos los miembros de nuestro equipo, en todos los departamentos y funciones. Mira c\u00f3mo estamos poniendo en pr\u00e1ctica nuestras cuatro prioridades de conservaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.flaquarium.org\\\/es\\\/conservacion\\\/lideres-en-conservacion\\\/prioridades-de-conservacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.flaquarium.org\\\/es\\\/conservacion\\\/lideres-en-conservacion\\\/prioridades-de-conservacion\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.flaquarium.org\\\/es\\\/conservacion\\\/lideres-en-conservacion\\\/prioridades-de-conservacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.flaquarium.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conservaci\u00f3n\",\"item\":\"https:\\\/\\\/www.flaquarium.org\\\/es\\\/conservacion\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L\u00edderes en conservaci\u00f3n\",\"item\":\"https:\\\/\\\/www.flaquarium.org\\\/es\\\/conservacion\\\/lideres-en-conservacion\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Prioridades de conservaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.flaquarium.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.flaquarium.org\\\/es\\\/\",\"name\":\"The Florida Aquarium\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.flaquarium.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prioridades de conservaci\u00f3n | The Florida Aquarium","description":"En The Florida Aquarium, la conservaci\u00f3n es una forma de vida para todos los miembros de nuestro equipo, en todos los departamentos y funciones. Mira c\u00f3mo estamos poniendo en pr\u00e1ctica nuestras cuatro prioridades de conservaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.flaquarium.org\/es\/conservacion\/lideres-en-conservacion\/prioridades-de-conservacion\/","og_locale":"es_ES","og_type":"article","og_title":"Prioridades de conservaci\u00f3n | The Florida Aquarium","og_description":"En The Florida Aquarium, la conservaci\u00f3n es una forma de vida para todos los miembros de nuestro equipo, en todos los departamentos y funciones. Mira c\u00f3mo estamos poniendo en pr\u00e1ctica nuestras cuatro prioridades de conservaci\u00f3n.","og_url":"https:\/\/www.flaquarium.org\/es\/conservacion\/lideres-en-conservacion\/prioridades-de-conservacion\/","og_site_name":"The Florida Aquarium","article_publisher":"https:\/\/www.facebook.com\/floridaaquarium","article_modified_time":"2026-02-09T19:57:58+00:00","twitter_card":"summary_large_image","twitter_site":"@floridaaquarium","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.flaquarium.org\/es\/conservacion\/lideres-en-conservacion\/prioridades-de-conservacion\/","url":"https:\/\/www.flaquarium.org\/es\/conservacion\/lideres-en-conservacion\/prioridades-de-conservacion\/","name":"Prioridades de conservaci\u00f3n | The Florida Aquarium","isPartOf":{"@id":"https:\/\/www.flaquarium.org\/es\/#website"},"datePublished":"2025-09-04T14:57:22+00:00","dateModified":"2026-02-09T19:57:58+00:00","description":"En The Florida Aquarium, la conservaci\u00f3n es una forma de vida para todos los miembros de nuestro equipo, en todos los departamentos y funciones. Mira c\u00f3mo estamos poniendo en pr\u00e1ctica nuestras cuatro prioridades de conservaci\u00f3n.","breadcrumb":{"@id":"https:\/\/www.flaquarium.org\/es\/conservacion\/lideres-en-conservacion\/prioridades-de-conservacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.flaquarium.org\/es\/conservacion\/lideres-en-conservacion\/prioridades-de-conservacion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.flaquarium.org\/es\/conservacion\/lideres-en-conservacion\/prioridades-de-conservacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.flaquarium.org\/es\/"},{"@type":"ListItem","position":2,"name":"Conservaci\u00f3n","item":"https:\/\/www.flaquarium.org\/es\/conservacion\/"},{"@type":"ListItem","position":3,"name":"L\u00edderes en conservaci\u00f3n","item":"https:\/\/www.flaquarium.org\/es\/conservacion\/lideres-en-conservacion\/"},{"@type":"ListItem","position":4,"name":"Prioridades de conservaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.flaquarium.org\/es\/#website","url":"https:\/\/www.flaquarium.org\/es\/","name":"The Florida Aquarium","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.flaquarium.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.flaquarium.org\/es\/wp-json\/wp\/v2\/pages\/25594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.flaquarium.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.flaquarium.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.flaquarium.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.flaquarium.org\/es\/wp-json\/wp\/v2\/comments?post=25594"}],"version-history":[{"count":3,"href":"https:\/\/www.flaquarium.org\/es\/wp-json\/wp\/v2\/pages\/25594\/revisions"}],"predecessor-version":[{"id":27872,"href":"https:\/\/www.flaquarium.org\/es\/wp-json\/wp\/v2\/pages\/25594\/revisions\/27872"}],"up":[{"embeddable":true,"href":"https:\/\/www.flaquarium.org\/es\/wp-json\/wp\/v2\/pages\/25570"}],"wp:attachment":[{"href":"https:\/\/www.flaquarium.org\/es\/wp-json\/wp\/v2\/media?parent=25594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}